{"id":11673,"date":"2025-03-04T14:53:50","date_gmt":"2025-03-04T06:53:50","guid":{"rendered":"https:\/\/delyava.com\/?page_id=11673"},"modified":"2025-04-16T17:58:36","modified_gmt":"2025-04-16T09:58:36","slug":"pigmentation","status":"publish","type":"page","link":"https:\/\/delyava.com\/pt\/pigmentation\/","title":{"rendered":"Pigmenta\u00e7\u00e3o"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"11673\" class=\"elementor elementor-11673\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8becd29 elementor-section-height-min-height elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"8becd29\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4727567\" data-id=\"4727567\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c03977f elementor-widget elementor-widget-heading\" data-id=\"c03977f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Pigmenta\u00e7\u00e3o<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b43ba1e elementor-widget elementor-widget-text-editor\" data-id=\"b43ba1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tTargeted laser breaks up dark spots and uneven pigment, revealing a brighter, more even complexion. Safe, effective, and tailored to your skin.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-43c665f e-flex e-con-boxed e-con e-parent\" data-id=\"43c665f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e605473 elementor-widget elementor-widget-heading\" data-id=\"e605473\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pigmenta\u00e7\u00e3o<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bff9eeb elementor-widget elementor-widget-text-editor\" data-id=\"bff9eeb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>O ciclo de vida da pele e as altera\u00e7\u00f5es hormonais afetam a distribui\u00e7\u00e3o da melanina na pele, levando a v\u00e1rios tipos de les\u00f5es hiperpigmentadas. Pintas, sardas, manchas da idade e melasma (uma condi\u00e7\u00e3o de hiperpigmenta\u00e7\u00e3o com manchas escuras no rosto) se enquadram nessa categoria. Normalmente, essas manchas significam que a pele foi danificada em v\u00e1rios graus. Sejam causadas pela exposi\u00e7\u00e3o ao sol, gen\u00e9tica ou outros fatores, elas acabam resultando em tom de pele irregular e manchas. Les\u00f5es cut\u00e2neas hiperpigmentadas s\u00e3o diferentes de les\u00f5es vasculares, que n\u00e3o s\u00e3o causadas por danos do sol e apresentam uma apar\u00eancia diferente dermatoscopicamente. Les\u00f5es hiperpigmentadas podem ser elevadas ou planas e geralmente s\u00e3o um problema cosm\u00e9tico e n\u00e3o m\u00e9dico. A luz intensa pulsada (LIP), que tem como alvo a melanina, \u00e9 eficaz no tratamento de les\u00f5es benignas e na sua elimina\u00e7\u00e3o.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fb35928 e-flex e-con-boxed e-con e-parent\" data-id=\"fb35928\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3d00d13 e-con-full e-flex e-con e-child\" data-id=\"3d00d13\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a19c4ac elementor-widget elementor-widget-heading\" data-id=\"a19c4ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Como funciona a remo\u00e7\u00e3o de les\u00f5es pigmentadas<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9ec2c00 e-con-full e-flex e-con e-child\" data-id=\"9ec2c00\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-05f1227 e-con-full e-flex e-con e-child\" data-id=\"05f1227\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-354fd35 e-con-full e-flex e-con e-child\" data-id=\"354fd35\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0957067 elementor-widget elementor-widget-image\" data-id=\"0957067\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/delyava.com\/wp-content\/uploads\/2025\/03\/How-Does-Pigmented-Lesion-Removal-Work-1-1024x768.jpeg\" class=\"attachment-large size-large wp-image-11696\" alt=\"Como funciona a remo\u00e7\u00e3o de les\u00f5es pigmentadas\" srcset=\"https:\/\/delyava.com\/wp-content\/uploads\/2025\/03\/How-Does-Pigmented-Lesion-Removal-Work-1-1024x768.jpeg 1024w, https:\/\/delyava.com\/wp-content\/uploads\/2025\/03\/How-Does-Pigmented-Lesion-Removal-Work-1-300x225.jpeg 300w, https:\/\/delyava.com\/wp-content\/uploads\/2025\/03\/How-Does-Pigmented-Lesion-Removal-Work-1-768x576.jpeg 768w, https:\/\/delyava.com\/wp-content\/uploads\/2025\/03\/How-Does-Pigmented-Lesion-Removal-Work-1-1536x1152.jpeg 1536w, https:\/\/delyava.com\/wp-content\/uploads\/2025\/03\/How-Does-Pigmented-Lesion-Removal-Work-1-2048x1536.jpeg 2048w, https:\/\/delyava.com\/wp-content\/uploads\/2025\/03\/How-Does-Pigmented-Lesion-Removal-Work-1-16x12.jpeg 16w, https:\/\/delyava.com\/wp-content\/uploads\/2025\/03\/How-Does-Pigmented-Lesion-Removal-Work-1-600x450.jpeg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Como funciona a remo\u00e7\u00e3o de les\u00f5es pigmentadas<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3637301 e-con-full e-flex e-con e-child\" data-id=\"3637301\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8f05ad6 elementor-widget elementor-widget-text-editor\" data-id=\"8f05ad6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"http:\/\/delyava.com\/pt\/\">Delya<\/a> utiliza luz avan\u00e7ada, laser e <a href=\"https:\/\/delyava.com\/pt\/\/shr-ipl-laser-system\/\">IPL<\/a> tecnologias para atingir precisamente a melanina em \u00e1reas opacas da pele, quebrando-a em part\u00edculas min\u00fasculas. Essas part\u00edculas s\u00e3o ent\u00e3o metabolizadas e removidas pelo sistema linf\u00e1tico, desintegrando gradualmente as camadas de pigmenta\u00e7\u00e3o e restaurando uma pele uniforme e sem falhas.<\/p><p>O tratamento leva em considera\u00e7\u00e3o a experi\u00eancia do paciente, \u00e9 altamente confort\u00e1vel, seguro e eficaz para todos os tipos e cores de pele, especialmente as mais escuras.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-609114c e-flex e-con-boxed e-con e-parent\" data-id=\"609114c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-fe9c162 e-con-full e-flex e-con e-child\" data-id=\"fe9c162\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-0895752 e-con-full e-flex e-con e-child\" data-id=\"0895752\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4403816 e-con-full e-flex e-con e-child\" data-id=\"4403816\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f1e9077 elementor-widget elementor-widget-text-editor\" data-id=\"f1e9077\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><span>O Procedimento de Pigmenta\u00e7\u00e3o<\/span><\/h2><p>Durante o tratamento, a luz intensa pulsada cobrir\u00e1 precisamente toda a \u00e1rea da les\u00e3o. As c\u00e9lulas da pele que est\u00e3o cheias de excesso de melanina absorvem a energia da luz intensa pulsada, aumentam a temperatura e come\u00e7am a degenerar. O tecido da pele normal ao redor permanece ileso. Ap\u00f3s o tratamento, a \u00e1rea tratada cura lentamente e o sistema imunol\u00f3gico varre as c\u00e9lulas mortas da pele, deixando a pele mais brilhante e sem falhas.<\/p><p>A dura\u00e7\u00e3o do tratamento depende do tamanho da les\u00e3o. Les\u00f5es menores, como manchas da idade, podem ser tratadas em um segundo, mas marcas de nascen\u00e7a ou pintas maiores podem levar alguns minutos. Os pacientes podem sentir um leve desconforto durante o tratamento, mas os efeitos colaterais s\u00e3o m\u00ednimos.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-523905c e-con-full e-flex e-con e-child\" data-id=\"523905c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5cdf6df elementor-widget elementor-widget-image\" data-id=\"5cdf6df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/delyava.com\/wp-content\/uploads\/2025\/03\/The-Pigmentation-Procedure.jpeg\" class=\"attachment-large size-large wp-image-11712\" alt=\"O Procedimento de Pigmenta\u00e7\u00e3o\" srcset=\"https:\/\/delyava.com\/wp-content\/uploads\/2025\/03\/The-Pigmentation-Procedure.jpeg 800w, https:\/\/delyava.com\/wp-content\/uploads\/2025\/03\/The-Pigmentation-Procedure-300x300.jpeg 300w, https:\/\/delyava.com\/wp-content\/uploads\/2025\/03\/The-Pigmentation-Procedure-150x150.jpeg 150w, https:\/\/delyava.com\/wp-content\/uploads\/2025\/03\/The-Pigmentation-Procedure-768x768.jpeg 768w, https:\/\/delyava.com\/wp-content\/uploads\/2025\/03\/The-Pigmentation-Procedure-12x12.jpeg 12w, https:\/\/delyava.com\/wp-content\/uploads\/2025\/03\/The-Pigmentation-Procedure-600x600.jpeg 600w, https:\/\/delyava.com\/wp-content\/uploads\/2025\/03\/The-Pigmentation-Procedure-100x100.jpeg 100w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">O Procedimento de Pigmenta\u00e7\u00e3o<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9dcf9ca e-flex e-con-boxed e-con e-parent\" data-id=\"9dcf9ca\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e98b030 e-con-full e-flex e-con e-child\" data-id=\"e98b030\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-650b702 elementor-widget elementor-widget-heading\" data-id=\"650b702\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Fotos de les\u00f5es de pigmenta\u00e7\u00e3o antes e depois<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8aa1975 e-con-full e-flex e-con e-child\" data-id=\"8aa1975\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-2181505 e-con-full e-flex e-con e-child\" data-id=\"2181505\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b1f76e7 elementor-widget elementor-widget-image\" data-id=\"b1f76e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"758\" height=\"556\" src=\"https:\/\/delyava.com\/wp-content\/uploads\/2025\/03\/Pigmentation-Lesions-Before-After-Pictures.png\" class=\"attachment-large size-large wp-image-11728\" alt=\"Fotos de les\u00f5es de pigmenta\u00e7\u00e3o antes e depois\" srcset=\"https:\/\/delyava.com\/wp-content\/uploads\/2025\/03\/Pigmentation-Lesions-Before-After-Pictures.png 758w, https:\/\/delyava.com\/wp-content\/uploads\/2025\/03\/Pigmentation-Lesions-Before-After-Pictures-300x220.png 300w, https:\/\/delyava.com\/wp-content\/uploads\/2025\/03\/Pigmentation-Lesions-Before-After-Pictures-16x12.png 16w, https:\/\/delyava.com\/wp-content\/uploads\/2025\/03\/Pigmentation-Lesions-Before-After-Pictures-600x440.png 600w\" sizes=\"(max-width: 758px) 100vw, 758px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Fotos de les\u00f5es de pigmenta\u00e7\u00e3o antes e depois<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-86de0c6 e-con-full e-flex e-con e-child\" data-id=\"86de0c6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8fd36d0 elementor-widget elementor-widget-text-editor\" data-id=\"8fd36d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A maioria das les\u00f5es hiperpigmentadas pode ser completamente removida com tratamentos suficientes. Les\u00f5es menores, como sardas e manchas da idade, provavelmente podem ser tratadas em uma \u00fanica sess\u00e3o; no entanto, outras les\u00f5es, devido a uma variedade de fatores, podem exigir at\u00e9 seis ou mais tratamentos para serem removidas.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9425251 e-con-full e-flex e-con e-child\" data-id=\"9425251\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-594c821 e-con-full e-flex e-con e-child\" data-id=\"594c821\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0867f58 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"0867f58\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"2560\" src=\"https:\/\/delyava.com\/wp-content\/uploads\/2025\/02\/intense-pulse-laser.png\" class=\"attachment-full size-full wp-image-10386\" alt=\"laser de pulso intenso\" srcset=\"https:\/\/delyava.com\/wp-content\/uploads\/2025\/02\/intense-pulse-laser.png 2560w, https:\/\/delyava.com\/wp-content\/uploads\/2025\/02\/intense-pulse-laser-300x300.png 300w, https:\/\/delyava.com\/wp-content\/uploads\/2025\/02\/intense-pulse-laser-1024x1024.png 1024w, https:\/\/delyava.com\/wp-content\/uploads\/2025\/02\/intense-pulse-laser-150x150.png 150w, https:\/\/delyava.com\/wp-content\/uploads\/2025\/02\/intense-pulse-laser-768x768.png 768w, https:\/\/delyava.com\/wp-content\/uploads\/2025\/02\/intense-pulse-laser-1536x1536.png 1536w, https:\/\/delyava.com\/wp-content\/uploads\/2025\/02\/intense-pulse-laser-2048x2048.png 2048w, https:\/\/delyava.com\/wp-content\/uploads\/2025\/02\/intense-pulse-laser-12x12.png 12w, https:\/\/delyava.com\/wp-content\/uploads\/2025\/02\/intense-pulse-laser-600x600.png 600w, https:\/\/delyava.com\/wp-content\/uploads\/2025\/02\/intense-pulse-laser-100x100.png 100w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Dispositivo de remo\u00e7\u00e3o de pelos SHR IPL<\/h3><p class=\"elementor-image-box-description\">Usando a tecnologia DPL, ele efetivamente encurta o caminho \u00f3ptico e reduz a densidade de pigmentos epid\u00e9rmicos. Ele aumenta a seguran\u00e7a, alivia efetivamente a dor, remove os pelos que s\u00e3o dif\u00edceis de remover com equipamentos comuns e melhora o rejuvenescimento da pele e a remo\u00e7\u00e3o de sardas. <\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c200ef2 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"c200ef2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/delyava.com\/pt\/products\/ipl-hair-removal-device\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ler mais<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-04b4cd9 e-con-full e-flex e-con e-child\" data-id=\"04b4cd9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fcee227 e-con-full e-flex e-con e-child\" data-id=\"fcee227\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Pigmentation Targeted laser breaks up dark spots and uneven pigment, revealing a brighter, more even complexion. Safe, effective, and tailored to your skin. Pigmentation The life cycle of the skin and hormonal changes affect the distribution of melanin in the skin, leading to various types of hyperpigmented lesions. Moles, freckles, age spots, and melasma (a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"class_list":["post-11673","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/delyava.com\/pt\/wp-json\/wp\/v2\/pages\/11673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/delyava.com\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/delyava.com\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/delyava.com\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/delyava.com\/pt\/wp-json\/wp\/v2\/comments?post=11673"}],"version-history":[{"count":9,"href":"https:\/\/delyava.com\/pt\/wp-json\/wp\/v2\/pages\/11673\/revisions"}],"predecessor-version":[{"id":17298,"href":"https:\/\/delyava.com\/pt\/wp-json\/wp\/v2\/pages\/11673\/revisions\/17298"}],"wp:attachment":[{"href":"https:\/\/delyava.com\/pt\/wp-json\/wp\/v2\/media?parent=11673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}